{"id":572,"date":"2023-04-21T18:35:44","date_gmt":"2023-04-21T16:35:44","guid":{"rendered":"https:\/\/anticavalserchio.gruppoflorence.it\/?page_id=572"},"modified":"2025-04-24T16:24:22","modified_gmt":"2025-04-24T14:24:22","slug":"lentreprise","status":"publish","type":"page","link":"https:\/\/anticavalserchio.gruppoflorence.it\/fr\/lentreprise\/","title":{"rendered":"L&rsquo;entreprise"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":13,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-572","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;entreprise - Antica Valserchio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/anticavalserchio.gruppoflorence.it\/fr\/lentreprise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;entreprise - Antica Valserchio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/anticavalserchio.gruppoflorence.it\/fr\/lentreprise\/\" \/>\n<meta property=\"og:site_name\" content=\"Antica Valserchio\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-24T14:24:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/anticavalserchio.gruppoflorence.it\\\/fr\\\/lentreprise\\\/\",\"url\":\"https:\\\/\\\/anticavalserchio.gruppoflorence.it\\\/fr\\\/lentreprise\\\/\",\"name\":\"L'entreprise - Antica Valserchio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anticavalserchio.gruppoflorence.it\\\/#website\"},\"datePublished\":\"2023-04-21T16:35:44+00:00\",\"dateModified\":\"2025-04-24T14:24:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anticavalserchio.gruppoflorence.it\\\/fr\\\/lentreprise\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/anticavalserchio.gruppoflorence.it\\\/fr\\\/lentreprise\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anticavalserchio.gruppoflorence.it\\\/fr\\\/lentreprise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/anticavalserchio.gruppoflorence.it\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;entreprise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anticavalserchio.gruppoflorence.it\\\/#website\",\"url\":\"https:\\\/\\\/anticavalserchio.gruppoflorence.it\\\/\",\"name\":\"Antica Valserchio\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/anticavalserchio.gruppoflorence.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'entreprise - Antica Valserchio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/anticavalserchio.gruppoflorence.it\/fr\/lentreprise\/","og_locale":"fr_FR","og_type":"article","og_title":"L'entreprise - Antica Valserchio","og_url":"https:\/\/anticavalserchio.gruppoflorence.it\/fr\/lentreprise\/","og_site_name":"Antica Valserchio","article_modified_time":"2025-04-24T14:24:22+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/anticavalserchio.gruppoflorence.it\/fr\/lentreprise\/","url":"https:\/\/anticavalserchio.gruppoflorence.it\/fr\/lentreprise\/","name":"L'entreprise - Antica Valserchio","isPartOf":{"@id":"https:\/\/anticavalserchio.gruppoflorence.it\/#website"},"datePublished":"2023-04-21T16:35:44+00:00","dateModified":"2025-04-24T14:24:22+00:00","breadcrumb":{"@id":"https:\/\/anticavalserchio.gruppoflorence.it\/fr\/lentreprise\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/anticavalserchio.gruppoflorence.it\/fr\/lentreprise\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/anticavalserchio.gruppoflorence.it\/fr\/lentreprise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/anticavalserchio.gruppoflorence.it\/fr\/"},{"@type":"ListItem","position":2,"name":"L&#8217;entreprise"}]},{"@type":"WebSite","@id":"https:\/\/anticavalserchio.gruppoflorence.it\/#website","url":"https:\/\/anticavalserchio.gruppoflorence.it\/","name":"Antica Valserchio","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/anticavalserchio.gruppoflorence.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/anticavalserchio.gruppoflorence.it\/fr\/wp-json\/wp\/v2\/pages\/572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anticavalserchio.gruppoflorence.it\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/anticavalserchio.gruppoflorence.it\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/anticavalserchio.gruppoflorence.it\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/anticavalserchio.gruppoflorence.it\/fr\/wp-json\/wp\/v2\/comments?post=572"}],"version-history":[{"count":9,"href":"https:\/\/anticavalserchio.gruppoflorence.it\/fr\/wp-json\/wp\/v2\/pages\/572\/revisions"}],"predecessor-version":[{"id":1237,"href":"https:\/\/anticavalserchio.gruppoflorence.it\/fr\/wp-json\/wp\/v2\/pages\/572\/revisions\/1237"}],"wp:attachment":[{"href":"https:\/\/anticavalserchio.gruppoflorence.it\/fr\/wp-json\/wp\/v2\/media?parent=572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}